{"id":21566,"date":"2024-02-14T00:00:00","date_gmt":"2024-02-14T00:00:00","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/"},"modified":"2024-02-14T00:00:00","modified_gmt":"2024-02-14T00:00:00","slug":"come-e-stato-distrutto-il-colosseo","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/","title":{"rendered":"Come \u00e8 stato distrutto il Colosseo?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/#Storia_del_Colosseo\" >Storia del Colosseo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/#Origine_del_Nome_Colosseo\" >Origine del Nome Colosseo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/#Curiosita_sulla_Costruzione\" >Curiosit\u00e0 sulla Costruzione<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Storia_del_Colosseo\"><\/span><strong>Storia del Colosseo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L&#8217;antica struttura croll\u00f2 solo per met\u00e0 a causa del terreno su cui poggia. Il crollo in s\u00e9 \u00e8 conseguenza di un catastrofico terremoto, con epicentro nell&#8217;Appennino Centrale, che si verific\u00f2 nel 1349. Altri danni furono prodotti dai terremoti del 442, 484, 1231, 1255, 1349 e 1703.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Origine_del_Nome_Colosseo\"><\/span><strong>Origine del Nome Colosseo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Colosseo Nome dato nel Medioevo all&#8217;anfiteatro Flavio , da sempre uno dei monumenti pi\u00f9 noti di Roma , inaugurato da Tito nell&#8217;80 d.C. Il nome deriva dalle dimensioni dell&#8217;edificio o, pi\u00f9 probabilmente, dalla vicinanza della statua colossale di Nerone.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Curiosita_sulla_Costruzione\"><\/span><strong>Curiosit\u00e0 sulla Costruzione<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Per costruirlo sono stati necessari poco pi\u00f9 di 5 anni: dal 75 all&#8217;80 d.C. Solo per la parete esterna sono stati utilizzati pi\u00f9 100 mila metri cubi di travertino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Storia del Colosseo L&#8217;antica struttura croll\u00f2 solo per met\u00e0 a causa del terreno su cui poggia. Il crollo in s\u00e9 \u00e8 conseguenza di un catastrofico terremoto, con epicentro nell&#8217;Appennino Centrale, che si verific\u00f2 nel 1349. Altri danni furono prodotti dai terremoti del 442, 484, 1231, 1255, 1349 e 1703. Origine del Nome Colosseo Colosseo Nome &#8230; <a title=\"Come \u00e8 stato distrutto il Colosseo?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/come-e-stato-distrutto-il-colosseo\/\" aria-label=\"Per saperne di pi\u00f9 su Come \u00e8 stato distrutto il Colosseo?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4132,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-21566","post","type-post","status-publish","format-standard","hentry","category-c"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/21566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/4132"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=21566"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/21566\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=21566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=21566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=21566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}