{"id":23464,"date":"2024-02-14T00:00:00","date_gmt":"2024-02-14T00:00:00","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/"},"modified":"2024-02-14T00:00:00","modified_gmt":"2024-02-14T00:00:00","slug":"come-si-certifica-lautismo","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/","title":{"rendered":"Come si certifica l&#8217;autismo?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/#Diagnosi_dellautismo\" >Diagnosi dell&#8217;autismo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/#Diagnosi_di_ADHD\" >Diagnosi di ADHD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/#Asperger_e_lintimita\" >Asperger e l&#8217;intimit\u00e0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/#Mente_di_un_Asperger\" >Mente di un Asperger<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/#Visione_del_mondo_di_un_Asperger\" >Visione del mondo di un Asperger<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Diagnosi_dellautismo\"><\/span>Diagnosi dell&#8217;autismo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L&#8217;accertamento della presenza di un disturbo dello spettro autistico (diagnosi) \u00e8 basato sull&#8217;osservazione del comportamento da parte di un medico specialista esperto.<\/p>\n<p>La diagnosi, generalmente, non viene formalizzata prima dei 3-4 anni di et\u00e0 e la sua definizione \u00e8 considerata affidabile gi\u00e0 a 24 mesi se condotta da personale esperto nel riconoscere i segnali di rischio.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Diagnosi_di_ADHD\"><\/span>Diagnosi di ADHD<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La diagnosi di ADHD \u00e8 fatta spesso fra le et\u00e0 3 e 6 in un bambino. Il clinico pu\u00f2 avere bisogno di di parlare con altri datori di cura per studiare dettagliatamente i problemi comportamentali del bambino.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Asperger_e_lintimita\"><\/span>Asperger e l&#8217;intimit\u00e0<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>In primo luogo un Asperger potrebbe vivere in maniera particolare l&#8217;intimit\u00e0 fisica e usare poche parole e gesti che esprimano amore o affetto. All&#8217;apparenza un Asperger potrebbe sembrare timido, ma questo accade soprattutto perch\u00e9 \u00e8 impacciato e non riesce a mantenere il contatto oculare.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Mente_di_un_Asperger\"><\/span>Mente di un Asperger<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Una mente cos\u00ec raffinata che non riesce a sintonizzarsi con la mente vicina. Quindi una vita costruita sulla fragilit\u00e0 nell&#8217;essere compreso. E nel non riuscire a comprendere il linguaggio emotivo dell&#8217;altro, l&#8217;interpretazione degli idiomi, delle metafore, della comunicazione e della reciprocit\u00e0.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Visione_del_mondo_di_un_Asperger\"><\/span>Visione del mondo di un Asperger<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il differente modo di vedere il mondo di un Asperger \u00e8 caratterizzato anche da una sensibilit\u00e0 sensoriale differente da quella \u201cnormale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diagnosi dell&#8217;autismo L&#8217;accertamento della presenza di un disturbo dello spettro autistico (diagnosi) \u00e8 basato sull&#8217;osservazione del comportamento da parte di un medico specialista esperto. La diagnosi, generalmente, non viene formalizzata prima dei 3-4 anni di et\u00e0 e la sua definizione \u00e8 considerata affidabile gi\u00e0 a 24 mesi se condotta da personale esperto nel riconoscere i &#8230; <a title=\"Come si certifica l&#8217;autismo?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/come-si-certifica-lautismo\/\" aria-label=\"Per saperne di pi\u00f9 su Come si certifica l&#8217;autismo?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4348,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-23464","post","type-post","status-publish","format-standard","hentry","category-c"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/23464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/4348"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=23464"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/23464\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=23464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=23464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=23464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}