{"id":27852,"date":"2024-02-15T00:00:00","date_gmt":"2024-02-15T00:00:00","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/"},"modified":"2024-02-15T00:00:00","modified_gmt":"2024-02-15T00:00:00","slug":"quale-decoder-per-tv-samsung","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/","title":{"rendered":"Quale decoder per TV Samsung?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/#Caratteristiche_principali_dei_decoder_DVB-TT2_HD\" >Caratteristiche principali dei decoder DVB-T\/T2 HD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/#Modelli_consigliati_di_decoder_per_il_2021\" >Modelli consigliati di decoder per il 2021<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/#Switch-off_e_nuovi_standard_TV\" >Switch-off e nuovi standard TV<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/#Utilizzo_e_connessione_del_decoder\" >Utilizzo e connessione del decoder<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Caratteristiche_principali_dei_decoder_DVB-TT2_HD\"><\/span>Caratteristiche principali dei decoder DVB-T\/T2 HD<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Tipologia: DVB-T\/T2 HD<\/li>\n<li>Formati supportati: MPEG-2, MPEG-4 H264\/AVC, H.265\/HEVC Main10<\/li>\n<li>Funzionalit\u00e0: EPG (Guida elettronica programmi TV), Televideo, Sottotitoli, Liste canali favoriti<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Modelli_consigliati_di_decoder_per_il_2021\"><\/span>Modelli consigliati di decoder per il 2021<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><strong>Decoder Trevi HE 3375 TS<\/strong>\n<ul>\n<li>Prezzo: circa 30 \u20ac<\/li>\n<li>Caratteristiche: piccolo, uscita SCART<\/li>\n<\/ul>\n<\/li>\n<li><strong>Decoder Edison Picco T265<\/strong><\/li>\n<li><strong>Decoder Digiprogress DPT203HD<\/strong><\/li>\n<li><strong>Decoder Strom 505 A DVB T2<\/strong><\/li>\n<li><strong>Decoder GT Media GTT-2 4K Android TV Box<\/strong><\/li>\n<li><strong>Decoder Digiquest Twin Tuner Rec<\/strong><\/li>\n<li><strong>Decoder GT Media V8 UHD<\/strong><\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"Switch-off_e_nuovi_standard_TV\"><\/span>Switch-off e nuovi standard TV<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il lancio del nuovo standard \u00e8 previsto per gennaio 2023. Il piano italiano prevede 3 fasi:<\/p>\n<ol>\n<li><strong>Fase 1:<\/strong> Abbandono graduale della codifica MPEG-2 a favore dell&#8217;MPEG-4<\/li>\n<li><strong>Fase 2:<\/strong> Test HEVC Main10 per verificare la compatibilit\u00e0 della TV con il nuovo digitale<\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"Utilizzo_e_connessione_del_decoder\"><\/span>Utilizzo e connessione del decoder<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Per far funzionare il decoder:<\/p>\n<ul>\n<li>Collega l&#8217;antenna all&#8217;ingresso RF<\/li>\n<li>Collega il cavo SCART al decoder e al TV<\/li>\n<li>Accendi il decoder e il televisore<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Caratteristiche principali dei decoder DVB-T\/T2 HD Tipologia: DVB-T\/T2 HD Formati supportati: MPEG-2, MPEG-4 H264\/AVC, H.265\/HEVC Main10 Funzionalit\u00e0: EPG (Guida elettronica programmi TV), Televideo, Sottotitoli, Liste canali favoriti Modelli consigliati di decoder per il 2021 Decoder Trevi HE 3375 TS Prezzo: circa 30 \u20ac Caratteristiche: piccolo, uscita SCART Decoder Edison Picco T265 Decoder Digiprogress DPT203HD Decoder &#8230; <a title=\"Quale decoder per TV Samsung?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/quale-decoder-per-tv-samsung\/\" aria-label=\"Per saperne di pi\u00f9 su Quale decoder per TV Samsung?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1084,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-27852","post","type-post","status-publish","format-standard","hentry","category-q"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/27852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/1084"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=27852"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/27852\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=27852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=27852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=27852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}