{"id":48422,"date":"2023-04-02T19:22:43","date_gmt":"2023-04-02T19:22:43","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/"},"modified":"2023-04-02T19:22:43","modified_gmt":"2023-04-02T19:22:43","slug":"che-cosa-fa-il-fisico","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/","title":{"rendered":"Che cosa fa il fisico?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Ruolo_del_Fisico\" >Ruolo del Fisico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Salario_di_un_Ingegnere_Aerospaziale\" >Salario di un Ingegnere Aerospaziale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Possibilita_di_Lavoro_per_un_Ingegnere_Aerospaziale\" >Possibilit\u00e0 di Lavoro per un Ingegnere Aerospaziale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Requisiti_per_Lavorare_per_la_NASA\" >Requisiti per Lavorare per la NASA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Lauree_piu_Prestigiose\" >Lauree pi\u00f9 Prestigiose<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Facolta_piu_Impegnative_in_Italia\" >Facolt\u00e0 pi\u00f9 Impegnative in Italia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/#Lauree_piu_Sfidanti\" >Lauree pi\u00f9 Sfidanti<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Ruolo_del_Fisico\"><\/span><strong>Ruolo del Fisico<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il <strong>Fisico<\/strong> svolge attivit\u00e0 di ricerca, consulenza, formazione e aggiornamento nelle varie discipline fisiche e nelle loro applicazioni nell&#8217;industria, nell&#8217;ambiente, nella sanit\u00e0, nei beni culturali e nella pubblica amministrazione. Esprime opinioni, crea e applica teorie, tecniche di calcolo, strumentazione e metodi di calcolo. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Salario_di_un_Ingegnere_Aerospaziale\"><\/span><strong>Salario di un Ingegnere Aerospaziale<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Qual \u00e8 il salario medio di un laureato in ingegneria aerospaziale? Un Ingegnere Aerospaziale pu\u00f2 guadagnare in media 43.800 \u20ac lordi all&#8217;anno (circa 2.180 \u20ac netti al mese), pi\u00f9 di 630 \u20ac (+41%) rispetto alla retribuzione mensile media in Italia. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Possibilita_di_Lavoro_per_un_Ingegnere_Aerospaziale\"><\/span><strong>Possibilit\u00e0 di Lavoro per un Ingegnere Aerospaziale<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cosa pu\u00f2 quindi fare un ingegnere aerospaziale? Un ingegnere aerospaziale pu\u00f2 trovare lavoro sia in centri di ricerca che in realt\u00e0 aerospaziali: aziende che sviluppano applicazioni e componenti per l&#8217;industria aerospaziale, come propulsori, sistemi di lancio, missili e satelliti, nonch\u00e9 software e equipaggiamenti elettronici per il pilotaggio.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Requisiti_per_Lavorare_per_la_NASA\"><\/span><strong>Requisiti per Lavorare per la NASA<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Come \u00e8 possibile lavorare per la NASA? Per ottenere il posto, oltre ad essere cittadini americani, civili o militari, devono soddisfare determinati requisiti. \u00c8 necessario avere una laurea in qualsiasi campo come matematica, ingegneria, fisica o biologia e almeno tre anni di esperienza lavorativa o mille ore di guida a bordo di un jet. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Lauree_piu_Prestigiose\"><\/span><strong>Lauree pi\u00f9 Prestigiose<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>In sintesi, le domande pi\u00f9 frequenti riguardano l&#8217;ingegneria al 93,9%, il medico o il professionista sanitario al 91,0%, l&#8217;architettura al 90,1%, l&#8217;economico-statistico al 89,7%, il chimico-farmaceutico al 89,5%, il scientifico al 88,2%, l&#8217;agricoltura e la veterinaria al 85,6% e il linguaggio al 85,2%.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Facolta_piu_Impegnative_in_Italia\"><\/span><strong>Facolt\u00e0 pi\u00f9 Impegnative in Italia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le universit\u00e0 pi\u00f9 impegnative in Italia sono:<\/p>\n<ul>\n<li>Ingegneria del volo.<\/li>\n<li>Fisica.<\/li>\n<li>Scienze della Chimica.<\/li>\n<li>Ingegneria dell&#8217;elettronica.<\/li>\n<li>Scienze della medicina.<\/li>\n<li>Scienze della vita, tecnologie della vita e biofarmaceutica.<\/li>\n<li>Veterinario.<\/li>\n<li>Fisico.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Lauree_piu_Sfidanti\"><\/span><strong>Lauree pi\u00f9 Sfidanti<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La laurea pi\u00f9 impegnativa \u00e8 quella di giurisprudenza, anche se offre molte opportunit\u00e0 di carriera e guadagno ma anche un alto tasso di disoccupazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ruolo del Fisico Il Fisico svolge attivit\u00e0 di ricerca, consulenza, formazione e aggiornamento nelle varie discipline fisiche e nelle loro applicazioni nell&#8217;industria, nell&#8217;ambiente, nella sanit\u00e0, nei beni culturali e nella pubblica amministrazione. Esprime opinioni, crea e applica teorie, tecniche di calcolo, strumentazione e metodi di calcolo. Salario di un Ingegnere Aerospaziale Qual \u00e8 il salario &#8230; <a title=\"Che cosa fa il fisico?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/che-cosa-fa-il-fisico\/\" aria-label=\"Per saperne di pi\u00f9 su Che cosa fa il fisico?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1404,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-48422","post","type-post","status-publish","format-standard","hentry","category-c"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/48422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/1404"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=48422"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/48422\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=48422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=48422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=48422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}