{"id":53453,"date":"2024-02-17T00:00:00","date_gmt":"2024-02-17T00:00:00","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/"},"modified":"2024-02-17T00:00:00","modified_gmt":"2024-02-17T00:00:00","slug":"cosa-cambia-tra-mma-e-boxe","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/","title":{"rendered":"Cosa cambia tra MMA e boxe?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/#Sport_di_contatto_e_il_DPCM\" >Sport di contatto e il DPCM<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/#Sport_di_contatto_popolari_in_Lombardia\" >Sport di contatto popolari in Lombardia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/#Tabella_per_la_scelta_dello_sport\" >Tabella per la scelta dello sport<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/#Il_pancrazio_nelle_Olimpiadi_antiche\" >Il pancrazio nelle Olimpiadi antiche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/#Sport_alle_Olimpiadi_moderne\" >Sport alle Olimpiadi moderne<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Sport_di_contatto_e_il_DPCM\"><\/span>Sport di contatto e il DPCM<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il Ministero dello Sport ha fornito chiarimenti sui sport di contatto vietati dal DPCM.<\/p>\n<ul>\n<li>Arti marziali come karate, aikido, judo e kungfu<\/li>\n<li>Attivit\u00e0 in acqua<\/li>\n<li>Basket<\/li>\n<li>Calcetto e calcio<\/li>\n<li>Canottaggio<\/li>\n<li>Cricket<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Sport_di_contatto_popolari_in_Lombardia\"><\/span>Sport di contatto popolari in Lombardia<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La Regione Lombardia ha regole specifiche per sport di contatto durante l&#8217;emergenza.<\/p>\n<ul>\n<li>Calcio, basket, pallavolo e sport di combattimento<\/li>\n<li>Cambiamenti nelle regole di allenamento<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Tabella_per_la_scelta_dello_sport\"><\/span>Tabella per la scelta dello sport<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Una tabella per aiutarti a scegliere lo sport pi\u00f9 adatto ai tuoi obiettivi.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Il_pancrazio_nelle_Olimpiadi_antiche\"><\/span>Il pancrazio nelle Olimpiadi antiche<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il pancrazio era uno sport totale alle Olimpiadi antiche, con tecniche consentite specifiche.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sport_alle_Olimpiadi_moderne\"><\/span>Sport alle Olimpiadi moderne<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Discipline sportive praticate oggi alle Olimpiadi moderne includono:<\/p>\n<ul>\n<li>Pugilato<\/li>\n<li>Calcio<\/li>\n<li>Vela<\/li>\n<li>Pentathlon moderno<\/li>\n<li>Scherma<\/li>\n<li>Tuffi<\/li>\n<li>Ciclismo<\/li>\n<li>Atletica<\/li>\n<li>Lotta greco-romana<\/li>\n<li>Equitazione<\/li>\n<li>Canottaggio<\/li>\n<li>Sollevamento pesi<\/li>\n<li>Lotta libera<\/li>\n<li>Hockey su prato<\/li>\n<li>Nuoto<\/li>\n<li>Ginnastica<\/li>\n<li>Pallanuoto<\/li>\n<li>Prima squadra femminile italiana alle Olimpiadi<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sport di contatto e il DPCM Il Ministero dello Sport ha fornito chiarimenti sui sport di contatto vietati dal DPCM. Arti marziali come karate, aikido, judo e kungfu Attivit\u00e0 in acqua Basket Calcetto e calcio Canottaggio Cricket Sport di contatto popolari in Lombardia La Regione Lombardia ha regole specifiche per sport di contatto durante l&#8217;emergenza. &#8230; <a title=\"Cosa cambia tra MMA e boxe?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/cosa-cambia-tra-mma-e-boxe\/\" aria-label=\"Per saperne di pi\u00f9 su Cosa cambia tra MMA e boxe?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-53453","post","type-post","status-publish","format-standard","hentry","category-c"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/53453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/4607"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=53453"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/53453\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=53453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=53453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=53453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}