{"id":73225,"date":"2024-02-02T05:51:21","date_gmt":"2024-02-02T05:51:21","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/"},"modified":"2024-02-02T05:51:21","modified_gmt":"2024-02-02T05:51:21","slug":"cosa-si-puo-suonare-con-la-chitarra-classica","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/","title":{"rendered":"Cosa si pu\u00f2 suonare con la chitarra classica?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/#Canzoni_per_Chitarra_Classica\" >Canzoni per Chitarra Classica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/#Strumenti_Acustici_e_Elettrici\" >Strumenti Acustici e Elettrici<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/#Band_e_Canzoni\" >Band e Canzoni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/#Chitarristi_Nirvana\" >Chitarristi Nirvana<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Canzoni_per_Chitarra_Classica\"><\/span>Canzoni per Chitarra Classica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Anima mia &#8211; Cugini di campagna<\/li>\n<li>Banane e lampone &#8211; Gianni Morandi<\/li>\n<li>Dance of Death &#8211; Iron Maiden<\/li>\n<li>Europa &#8211; Carlos Santana<\/li>\n<li>Non piangere &#8211; Guns N&#8217; Roses<\/li>\n<li>La paura del buio &#8211; Iron Maiden<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Strumenti_Acustici_e_Elettrici\"><\/span>Strumenti Acustici e Elettrici<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><strong>Plettro e Significato Acustico<\/strong>\n<ul>\n<li>Un piccolo arnese di legno o avorio utilizzato dagli antichi Greci<\/li>\n<li>Musica acustica: usa strumenti che producono suono in modo acustico<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"Band_e_Canzoni\"><\/span>Band e Canzoni<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\n<p><strong>Green Day<\/strong><\/p>\n<ul>\n<li>American Idiot<\/li>\n<li>Boulevard Of Broken Dreams<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><strong>Nirvana<\/strong><\/p>\n<ul>\n<li>Nirvana, come sei<\/li>\n<li>In riferimento a una ragazza<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><strong>Altre Band<\/strong><\/p>\n<ul>\n<li>Children Of The Damned &#8211; Iron Maiden<\/li>\n<li>Anarchy In the United Kingdom &#8211; The Sex Pistols<\/li>\n<li>AC\/DC<\/li>\n<li>Joe Satriani torna a Shalla Bal<\/li>\n<li>Bop Blitzkrieg &#8211; Ramones<\/li>\n<li>Amen &#8211; Ben Harper<\/li>\n<li>Bambini non piangiamo &#8211; The Cure<\/li>\n<li>Cats in the Cradle &#8211; Poor Kid Joe<\/li>\n<li>Don&#8217;t Cry &#8211; Guns N&#8217; Roses<\/li>\n<li>In ogni luogo &#8211; Michelle Branch<\/li>\n<li>Fade to Black &#8211; Metallica<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Chitarristi_Nirvana\"><\/span>Chitarristi Nirvana<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Kurt Cobain: fondatore e chitarrista<\/li>\n<li>Krist Novoselic: bassista<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Canzoni per Chitarra Classica Anima mia &#8211; Cugini di campagna Banane e lampone &#8211; Gianni Morandi Dance of Death &#8211; Iron Maiden Europa &#8211; Carlos Santana Non piangere &#8211; Guns N&#8217; Roses La paura del buio &#8211; Iron Maiden Strumenti Acustici e Elettrici Plettro e Significato Acustico Un piccolo arnese di legno o avorio utilizzato &#8230; <a title=\"Cosa si pu\u00f2 suonare con la chitarra classica?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/cosa-si-puo-suonare-con-la-chitarra-classica\/\" aria-label=\"Per saperne di pi\u00f9 su Cosa si pu\u00f2 suonare con la chitarra classica?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":2272,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-73225","post","type-post","status-publish","format-standard","hentry","category-c"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/73225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/2272"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=73225"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/73225\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=73225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=73225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=73225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}