{"id":90926,"date":"2024-02-22T00:00:00","date_gmt":"2024-02-22T00:00:00","guid":{"rendered":"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/"},"modified":"2024-02-22T00:00:00","modified_gmt":"2024-02-22T00:00:00","slug":"a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a","status":"publish","type":"post","link":"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/","title":{"rendered":"A quale tipo di combustibile e associata la classe di fuoco a?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/#Classificazione_degli_Incendi\" >Classificazione degli Incendi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/#Differenza_tra_Temperatura_di_Infiammabilita_e_di_Accensione\" >Differenza tra Temperatura di Infiammabilit\u00e0 e di Accensione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/#Conservazione_e_Proprieta_della_Benzina\" >Conservazione e Propriet\u00e0 della Benzina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/#Conservazione_del_Gasolio_e_Additivi_Antighiaccio\" >Conservazione del Gasolio e Additivi Antighiaccio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/#Resistenza_del_Petrolio_al_Congelamento\" >Resistenza del Petrolio al Congelamento<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Classificazione_degli_Incendi\"><\/span>Classificazione degli Incendi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La classe A include gli incendi causati da materiali solidi come legna, carta, carbone, pelli, materie plastiche, gomma e altri derivati. La combustione pu\u00f2 avvenire in due modi diversi: combustibile in combustione.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Differenza_tra_Temperatura_di_Infiammabilita_e_di_Accensione\"><\/span>Differenza tra Temperatura di Infiammabilit\u00e0 e di Accensione<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La temperatura di infiammabilit\u00e0 \u00e8 la temperatura pi\u00f9 bassa alla quale il vapore di un materiale si accende in presenza di una sorgente di accensione, mentre la temperatura di autoaccensione \u00e8 la temperatura a cui il materiale prende fuoco spontaneamente.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Conservazione_e_Proprieta_della_Benzina\"><\/span>Conservazione e Propriet\u00e0 della Benzina<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La benzinasi conserva in buone condizioni se \u00e8 custodita in un ambiente fresco e asciutto, al riparo dalla luce diretta del sole e per non pi\u00f9 di trenta giorni. La benzina \u00e8 prodotta dalla distillazione del petrolio grezzo a temperature tra 35 e 215 gradi Celsius.        <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Conservazione_del_Gasolio_e_Additivi_Antighiaccio\"><\/span>Conservazione del Gasolio e Additivi Antighiaccio<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Per evitare che il gasolio si congel, aggiungere un additivo specifico al serbatoio dell&#8217;auto, se gi\u00e0 pieno di gasolio, migliorando le caratteristiche delle basse temperature dei carburanti.            <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Resistenza_del_Petrolio_al_Congelamento\"><\/span>Resistenza del Petrolio al Congelamento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il combustibile comune nei distributori contiene additivi per resistere a temperature fino a 12 gradi sotto lo zero nei mesi invernali da novembre a marzo. La temperatura del carburante nel serbatoio non \u00e8 quella dell&#8217;aria esterna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Classificazione degli Incendi La classe A include gli incendi causati da materiali solidi come legna, carta, carbone, pelli, materie plastiche, gomma e altri derivati. La combustione pu\u00f2 avvenire in due modi diversi: combustibile in combustione. Differenza tra Temperatura di Infiammabilit\u00e0 e di Accensione La temperatura di infiammabilit\u00e0 \u00e8 la temperatura pi\u00f9 bassa alla quale il &#8230; <a title=\"A quale tipo di combustibile e associata la classe di fuoco a?\" class=\"read-more\" href=\"https:\/\/gufosaggio.net\/i\/a-quale-tipo-di-combustibile-e-associata-la-classe-di-fuoco-a\/\" aria-label=\"Per saperne di pi\u00f9 su A quale tipo di combustibile e associata la classe di fuoco a?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":663,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-90926","post","type-post","status-publish","format-standard","hentry","category-a"],"_links":{"self":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/90926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/comments?post=90926"}],"version-history":[{"count":0,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/posts\/90926\/revisions"}],"wp:attachment":[{"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/media?parent=90926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/categories?post=90926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gufosaggio.net\/i\/wp-json\/wp\/v2\/tags?post=90926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}